{"id":13967,"date":"2026-03-09T05:00:08","date_gmt":"2026-03-09T04:00:08","guid":{"rendered":"https:\/\/schulebza.de\/gymnasium\/?p=13967"},"modified":"2026-03-09T06:03:38","modified_gmt":"2026-03-09T05:03:38","slug":"mottowoche-digital-clean-up","status":"publish","type":"post","link":"https:\/\/schulebza.de\/gymnasium\/2026\/03\/09\/mottowoche-digital-clean-up\/","title":{"rendered":"Mottowoche &#8211; Digital Clean-up"},"content":{"rendered":"<div class=\"postie-post\">\n<div>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-4-3 su-image-carousel-has-lightbox su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-photo su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"max-width:800px\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":3000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025000000000000001387778780781445675529539585113525390625,\"friction\":0.2800000000000000266453525910037569701671600341796875}' id=\"su_image_carousel_6a04e6bf8fc46\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/4.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"\"><img decoding=\"async\" width=\"1024\" height=\"707\" src=\"https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/4-1024x707.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/4-1024x707.jpg 1024w, https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/4-300x207.jpg 300w, https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/4-768x530.jpg 768w, https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/4-1536x1061.jpg 1536w, https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/4.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><a href=\"https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/3.jpg\" target=\"_blank\" rel=\"noopener noreferrer\" data-caption=\"\"><img decoding=\"async\" width=\"1024\" height=\"707\" src=\"https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/3-1024x707.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/3-1024x707.jpg 1024w, https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/3-300x207.jpg 300w, https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/3-768x530.jpg 768w, https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/3-1536x1061.jpg 1536w, https:\/\/schulebza.de\/gymnasium\/wp-content\/uploads\/2026\/03\/3.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><script id=\"su_image_carousel_6a04e6bf8fc46_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a04e6bf8fc46\"))}, 0);}var su_image_carousel_6a04e6bf8fc46_script=document.getElementById(\"su_image_carousel_6a04e6bf8fc46_script\");if(su_image_carousel_6a04e6bf8fc46_script){su_image_carousel_6a04e6bf8fc46_script.parentNode.removeChild(su_image_carousel_6a04e6bf8fc46_script);}<\/script>Verzicht auf KI &#8211; das ist nachhaltig. Aber wie?<\/p>\n<p>Wir alle kennen das Problem: Der Cloud Speicher ist voll! &#8211; Wir haben hier eine L\u00f6sung. Bereinigt eure Cloud von unn\u00f6tigen Fotos. Dabei entm\u00fcllt ihr nicht nur euer Handy, sondern seid auch richtig umweltfreundlich. Ihr k\u00f6nnt sogar noch mehr f\u00fcr die Umwelt tun. Verzichtet doch f\u00fcr eine Woche auf KI und nutzt Suchmaschinen wie zum Beispiel Startpage. So spart ihr Wasser und Strom in den Rechenzentren und verringert die CO2-Emissionen.<\/p>\n<p>Gestaltet euren Lebensstil nachhaltiger! Ganz einfach und bequem von der Couch aus!<\/p>\n<p style=\"text-align: right;\"><em>Sophie, Samira, Adriano &amp; Jonas\u00a0<\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Verzicht auf KI &#8211; das ist nachhaltig. Aber wie? Wir alle kennen das Problem: Der Cloud Speicher ist voll! &#8211; Wir haben hier eine L\u00f6sung. Bereinigt eure Cloud von unn\u00f6tigen Fotos. Dabei entm\u00fcllt ihr nicht nur euer Handy, sondern seid auch richtig umweltfreundlich. Ihr k\u00f6nnt sogar noch mehr f\u00fcr die Umwelt tun. Verzichtet doch f\u00fcr&#8230;<\/p>\n<p class=\"more-link\"><a href=\"https:\/\/schulebza.de\/gymnasium\/2026\/03\/09\/mottowoche-digital-clean-up\/\" class=\"\"><span>Weiterlesen<\/span><i>&#43;<\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13967","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/schulebza.de\/gymnasium\/wp-json\/wp\/v2\/posts\/13967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schulebza.de\/gymnasium\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schulebza.de\/gymnasium\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schulebza.de\/gymnasium\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schulebza.de\/gymnasium\/wp-json\/wp\/v2\/comments?post=13967"}],"version-history":[{"count":2,"href":"https:\/\/schulebza.de\/gymnasium\/wp-json\/wp\/v2\/posts\/13967\/revisions"}],"predecessor-version":[{"id":13972,"href":"https:\/\/schulebza.de\/gymnasium\/wp-json\/wp\/v2\/posts\/13967\/revisions\/13972"}],"wp:attachment":[{"href":"https:\/\/schulebza.de\/gymnasium\/wp-json\/wp\/v2\/media?parent=13967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schulebza.de\/gymnasium\/wp-json\/wp\/v2\/categories?post=13967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schulebza.de\/gymnasium\/wp-json\/wp\/v2\/tags?post=13967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}